{"id":58672,"date":"2024-07-30T13:52:20","date_gmt":"2024-07-30T13:52:20","guid":{"rendered":"https:\/\/galland-sas.com\/?post_type=produitcpt&#038;p=58672"},"modified":"2024-09-13T15:56:38","modified_gmt":"2024-09-13T15:56:38","slug":"at-jg1441-jg1887-jg1892","status":"publish","type":"produitcpt","link":"https:\/\/galland-sas.com\/zh\/produit\/at-jg1441-jg1887-jg1892\/","title":{"rendered":"JG1441\/JG1887\/JG1892"},"content":{"rendered":"<p>\u4f5c\u4e3a\u60ac\u94fe\u7ebf\u7cfb\u7edf\u7684\u91cd\u8981\u7ec4\u6210\u90e8\u5206\uff0c\u6211\u4eec\u7684\u5f20\u7d27\u88c5\u7f6e\u662f\u4ece\u6700\u521d\u51e0\u5e74\u7684\u6d3b\u52a8\u4e2d\u5f00\u53d1\u51fa\u6765\u7684\u3002\u5728\u83b7\u5f97 SNCF \u4f9b\u5e94\u5546\u8ba4\u8bc1\u540e\uff0c\u6211\u4eec\u7ee7\u7eed\u5f00\u53d1\u5e76\u6269\u5927\u4e86\u6211\u4eec\u7684\u4ea7\u54c1\u8303\u56f4\u3002\u8fc4\u4eca\u4e3a\u6b62\uff0c\u6211\u4eec\u63d0\u4f9b\u91c7\u7528\u4e24\u79cd\u6280\u672f\u7684\u5f20\u7d27\u88c5\u7f6e\uff1a<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u673a\u68b0\uff1aAT \u5e26\u9a6c\u5f17\u3001\u5f39\u7c27\u6216\u7ede\u76d8\uff0c\u5e26\u6216\u4e0d\u5e26\u6da6\u6ed1\u3002<\/li>\n\n\n\n<li>\u6cb9\u6c14\u52a8\uff1a\u4f7f\u7528 AERO 480 \u548c AERO 1000\u3002<\/li>\n<\/ul>\n\n\n\n<p>\u9632\u5760\u843d\u7cfb\u7edf\u548c\u63a7\u5236\u6761\u53ef\u4f9b\u9009\u62e9\u3002<br>JG1441\u3001JG1887 \u548c JG1892 \u76ae\u5e26\u8f6e\u5f20\u7d27\u5668\u63d0\u4f9b 1\/3 \u7684\u51cf\u901f\u6bd4\u3002<\/p>","protected":false},"excerpt":{"rendered":"<p>Pi\u00e8ces essentielles au syst\u00e8me cat\u00e9naire, nos appareils tendeurs ont \u00e9t\u00e9 d\u00e9velopp\u00e9s d\u00e8s les premi\u00e8res ann\u00e9es d\u2019activit\u00e9. Apr\u00e8s avoir \u00e9t\u00e9 certifi\u00e9s en tant que fournisseur de la SNCF, nous avons poursuivi les d\u00e9veloppements et \u00e9toff\u00e9 notre gamme de produits. A ce jour, nous d\u00e9clinons les appareils tendeurs selon deux technologies : Des syst\u00e8mes anti-chutes et des r\u00e9glettes de contr\u00f4le sont disponibles&hellip;<\/p>","protected":false},"author":1,"featured_media":58665,"template":"","cat_produit":[4],"tens_produit":[12,14,13,11],"at_produit":[15],"bras_produit":[],"class_list":["post-58672","produitcpt","type-produitcpt","status-publish","has-post-thumbnail","hentry","cat_produit-appareil-tendeur","tens_produit-1500v","tens_produit-25kv","tens_produit-3000v","tens_produit-750v","at_produit-rapport-3","entry"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte.jpg",1999,2000,false],"thumbnail":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-150x150.jpg",150,150,true],"medium":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-300x300.jpg",300,300,true],"medium_large":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-768x768.jpg",768,768,true],"large":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte.jpg",1999,2000,false],"trp-custom-language-flag":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-12x12.jpg",12,12,true],"largexl":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-1023x1024.jpg",1023,1024,true],"post-thumbnail":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/07\/AT05-A-JG1441-CC-ind-B-AT-1-3-Chape-courte-1568x1569.jpg",1568,1569,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/galland-sas.com\/zh\/author\/dfuzionadmin\/"},"uagb_comment_info":0,"uagb_excerpt":"Pi\u00e8ces essentielles au syst\u00e8me cat\u00e9naire, nos appareils tendeurs ont \u00e9t\u00e9 d\u00e9velopp\u00e9s d\u00e8s les premi\u00e8res ann\u00e9es d\u2019activit\u00e9. Apr\u00e8s avoir \u00e9t\u00e9 certifi\u00e9s en tant que fournisseur de la SNCF, nous avons poursuivi les d\u00e9veloppements et \u00e9toff\u00e9 notre gamme de produits. A ce jour, nous d\u00e9clinons les appareils tendeurs selon deux technologies : Des syst\u00e8mes anti-chutes et des&hellip;","_links":{"self":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt\/58672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt"}],"about":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/types\/produitcpt"}],"author":[{"embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt\/58672\/revisions"}],"predecessor-version":[{"id":58673,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt\/58672\/revisions\/58673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/media\/58665"}],"wp:attachment":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/media?parent=58672"}],"wp:term":[{"taxonomy":"cat_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/cat_produit?post=58672"},{"taxonomy":"tens_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/tens_produit?post=58672"},{"taxonomy":"at_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/at_produit?post=58672"},{"taxonomy":"bras_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/bras_produit?post=58672"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}