{"id":59061,"date":"2024-08-20T10:33:05","date_gmt":"2024-08-20T10:33:05","guid":{"rendered":"https:\/\/galland-sas.com\/?post_type=produitcpt&#038;p=59061"},"modified":"2024-09-23T07:50:47","modified_gmt":"2024-09-23T07:50:47","slug":"jg1352-2","status":"publish","type":"produitcpt","link":"https:\/\/galland-sas.com\/zh\/produit\/jg1352-2\/","title":{"rendered":"JG1352\/211626"},"content":{"rendered":"<p>\u4f5c\u4e3a Galland \u6280\u672f\u7684\u5173\u952e\u7ec4\u6210\u90e8\u5206\uff0c\u5206\u6bb5\u7edd\u7f18\u5b50\u4e00\u76f4\u662f\u6211\u4eec\u82b1\u8d39\u5927\u91cf\u65f6\u95f4\u8fdb\u884c\u7814\u53d1\u7684\u4e3b\u9898\u3002\u6211\u4eec\u4e0e France \u548c\u56fd\u9645\u4e3b\u8981\u94c1\u8def\u516c\u53f8\u4e00\u8d77\u6269\u5c55\u4e86\u6211\u4eec\u7684\u8303\u56f4\u5e76\u6539\u8fdb\u4e86\u6211\u4eec\u7684\u7cfb\u7edf\u3002\u6211\u4eec\u7684\u76ee\u6807\u662f\u901a\u8fc7\u9ad8\u6548\u3001\u8010\u7528\u4e14\u6613\u4e8e\u5b89\u88c5\u7684\u7cfb\u7edf\u6765\u6ee1\u8db3\u5ba2\u6237\u7684\u9700\u6c42\u3002<\/p>\n\n\n\n<p>L&rsquo;isolateur de section JG1352 est con\u00e7u pour des infrastructures cat\u00e9naires aliment\u00e9es en courant alternatif: 25 kV AC ou 15 kV AC.<\/p>","protected":false},"excerpt":{"rendered":"<p>Composant cl\u00e9 du savoir-faire Galland, l\u2019isolateur de section a fait l\u2019objet de nombreuses heures de R&amp;D. Nous avons \u00e9tendu notre gamme et fait \u00e9voluer nos syst\u00e8mes aux c\u00f4t\u00e9s d\u2019acteurs ferroviaires majeurs en France et \u00e0 l\u2019international. Notre objectif est de r\u00e9pondre aux demandes de nos clients \u00e0 travers des syst\u00e8mes performants, durables et faciles d\u2019installation. L&rsquo;isolateur de section JG1352 est&hellip;<\/p>","protected":false},"author":1,"featured_media":59396,"template":"","cat_produit":[3],"tens_produit":[14],"at_produit":[],"bras_produit":[],"class_list":["post-59061","produitcpt","type-produitcpt","status-publish","has-post-thumbnail","hentry","cat_produit-isolateur-section","tens_produit-25kv","entry"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions.jpg",2000,2000,false],"thumbnail":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-150x150.jpg",150,150,true],"medium":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-300x300.jpg",300,300,true],"medium_large":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-768x768.jpg",768,768,true],"large":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions.jpg",2000,2000,false],"trp-custom-language-flag":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-12x12.jpg",12,12,true],"largexl":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-1024x1024.jpg",1024,1024,true],"post-thumbnail":["https:\/\/galland-sas.com\/wp-content\/uploads\/2024\/08\/IS06A-JG1352-ind-K-IS-25-kV-suspensions-1568x1568.jpg",1568,1568,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/galland-sas.com\/zh\/author\/dfuzionadmin\/"},"uagb_comment_info":0,"uagb_excerpt":"Composant cl\u00e9 du savoir-faire Galland, l\u2019isolateur de section a fait l\u2019objet de nombreuses heures de R&amp;D. Nous avons \u00e9tendu notre gamme et fait \u00e9voluer nos syst\u00e8mes aux c\u00f4t\u00e9s d\u2019acteurs ferroviaires majeurs en France et \u00e0 l\u2019international. Notre objectif est de r\u00e9pondre aux demandes de nos clients \u00e0 travers des syst\u00e8mes performants, durables et faciles d\u2019installation.&hellip;","_links":{"self":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt\/59061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt"}],"about":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/types\/produitcpt"}],"author":[{"embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt\/59061\/revisions"}],"predecessor-version":[{"id":59160,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/produitcpt\/59061\/revisions\/59160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/media\/59396"}],"wp:attachment":[{"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/media?parent=59061"}],"wp:term":[{"taxonomy":"cat_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/cat_produit?post=59061"},{"taxonomy":"tens_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/tens_produit?post=59061"},{"taxonomy":"at_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/at_produit?post=59061"},{"taxonomy":"bras_produit","embeddable":true,"href":"https:\/\/galland-sas.com\/zh\/wp-json\/wp\/v2\/bras_produit?post=59061"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}